{"id":9885,"date":"2021-03-09T14:48:09","date_gmt":"2021-03-09T14:48:09","guid":{"rendered":"https:\/\/www.nicolacrivellari.com\/?page_id=9885"},"modified":"2021-03-11T13:35:55","modified_gmt":"2021-03-11T13:35:55","slug":"dodo","status":"publish","type":"page","link":"https:\/\/www.nicolacrivellari.com\/en\/dodo\/","title":{"rendered":"Dodo Jewels"},"content":{"rendered":"<div class=\"slider-wrapper relative\" id=\"slider-177277303\" >\n    <div class=\"slider slider-nav-circle slider-nav-large slider-nav-light slider-style-normal\"\n        data-flickity-options='{\n            \"cellAlign\": \"center\",\n            \"imagesLoaded\": true,\n            \"lazyLoad\": 1,\n            \"freeScroll\": false,\n            \"wrapAround\": true,\n            \"autoPlay\": 6000,\n            \"pauseAutoPlayOnHover\" : true,\n            \"prevNextButtons\": false,\n            \"contain\" : true,\n            \"adaptiveHeight\" : true,\n            \"dragThreshold\" : 10,\n            \"percentPosition\": true,\n            \"pageDots\": false,\n            \"rightToLeft\": false,\n            \"draggable\": false,\n            \"selectedAttraction\": 0.1,\n            \"parallax\" : 0,\n            \"friction\": 0.6        }'\n        >\n        \n\n  <div class=\"banner has-hover has-video sticky-section is-full-height has-parallax\" id=\"banner-1563207595\">\n          <div class=\"banner-inner fill\">\n        <div class=\"banner-bg fill\" data-parallax=\"-10\" data-parallax-container=\".banner\" data-parallax-background>\n            <div class=\"bg fill bg-fill \"><\/div>\n            \t<div class=\"video-overlay no-click fill visible\"><\/div>\n\t<video class=\"video-bg fill visible\" preload playsinline autoplay\n\t\tmuted\t\tloop>\n\t\t<source src=\"https:\/\/www.nicolacrivellari.com\/wp-content\/uploads\/2020\/08\/Dodo_Cover.mp4\" type=\"video\/mp4\">\t<\/video>\n                        \n                    <\/div>\n        <div class=\"banner-layers container\">\n            <div class=\"fill banner-link\"><\/div>            \n\t<div class=\"img has-hover x50 md-x50 lg-x50 y95 md-y95 lg-y95\" id=\"image_507905811\">\n\t\t<a class=\"\" href=\"https:\/\/www.nicolacrivellari.com\/#progetto\"  >\t\t\t\t\t\t<div class=\"img-inner dark\" >\n\t\t\t<img width=\"60\" height=\"31\" src=\"https:\/\/www.nicolacrivellari.com\/wp-content\/uploads\/2020\/09\/arrow_down_small.png\" class=\"attachment-original size-original\" alt=\"scroll_down\" loading=\"lazy\" \/>\t\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/a>\t\t\n<style>\n#image_507905811 {\n  width: 4%;\n}\n<\/style>\n\t<\/div>\n\t\n        <\/div>\n      <\/div>\n\n            \n<style>\n#banner-1563207595 {\n  padding-top: 100%;\n}\n#banner-1563207595 .bg.bg-loaded {\n  background-image: url(https:\/\/www.nicolacrivellari.com\/wp-content\/uploads\/2020\/08\/5_Dodo_risultato-1024x576.jpg);\n}\n<\/style>\n  <\/div>\n\n\n     <\/div>\n\n     <div class=\"loading-spin dark large centered\"><\/div>\n\n     <\/div>\n\n\n<span class=\"scroll-to\" data-label=\"Scroll to: #progetto\" data-bullet=\"true\" data-link=\"#progetto\" data-title=\"progetto\"><a name=\"progetto\"><\/a><\/span>\n\t<section class=\"section\" id=\"section_1957435505\">\n\t\t<div class=\"bg section-bg fill bg-fill  bg-loaded\" >\n\n\t\t\t\n\t\t\t\n\t\t\t\n\n\t\t<\/div>\n\n\t\t<div class=\"section-content relative\">\n\t\t\t\n<div class=\"row align-middle align-center\" style=\"max-width:800px\" id=\"row-1776761495\">\n\n\t<div id=\"col-1866841479\" class=\"col small-12 large-12\"  >\n\t\t<div class=\"col-inner text-left\"  >\n\t\t\t\n\t\t\t\n<h1><span style=\"color: #ffffff; font-size: 150%;\"><span class=\"texteditor-inline-fontsize\">DoDo Jewels<\/span><\/span><\/h1>\n<h3>Charm the World.<\/h3>\n<p>Instagram nowadays is the social network with the greatest appeal among young adults and, thanks to the shoppable posts, an extremely powerful marketing platform. For Dodo I created content for Instagram stories and paid advertising.<br \/> A project by Paola Manfrin, creative director of Ego by WHITE, RED &amp; GREEN.<\/p>\n\t\t<\/div>\n\t\t\t<\/div>\n\n\t\n<\/div>\n<div class=\"row\"  id=\"row-2093173720\">\n\n\t<div id=\"col-1305501490\" class=\"col small-12 large-12\"  >\n\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n<div class=\"containervideo2\"><iframe class=\"responsive-iframe\" src=\"https:\/\/www.youtube.com\/embed\/1QNbS5UP9oE?rel=0\" allowfullscreen=\"\" frameborder=\"0\"><br \/>\n<\/iframe>\n<\/div>\n\t\t<\/div>\n\t\t\t<\/div>\n\n\t\n<\/div>\n<div class=\"row\"  id=\"row-1040593503\">\n\n\t<div id=\"col-1715482969\" class=\"col small-12 large-12\"  >\n\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n<div class=\"containervideo2\"><iframe class=\"responsive-iframe\" src=\"https:\/\/www.youtube.com\/embed\/mxznF9MK51s?rel=0\" allowfullscreen=\"\" frameborder=\"0\"><br \/>\n<\/iframe>\n<\/div>\n\t\t<\/div>\n\t\t\t<\/div>\n\n\t\n<\/div>\n<div class=\"row align-middle align-center\" style=\"max-width:800px\" id=\"row-1910391269\">\n\n\t<div id=\"col-368654688\" class=\"col small-12 large-12\"  >\n\t\t<div class=\"col-inner text-left\"  >\n\t\t\t\n\t\t\t\n<h3><span style=\"color: #ffffff; font-size: 100%;\">Credits<\/span><\/h3>\n<p>Agency: Ego by WHITE, RED &amp; GREEN.<\/br> Creative Director: Paola Manfrin.<\/br> My role: motion graphics, sound design.<\/p>\n\t\t<\/div>\n\t\t\t<\/div>\n\n\t\n<\/div>\n\t\t<\/div>\n\n\t\t\n<style>\n#section_1957435505 {\n  padding-top: 30px;\n  padding-bottom: 30px;\n  background-color: rgb(33, 33, 33);\n}\n<\/style>\n\t<\/section>\n\t\n\t<section class=\"section hide-for-small\" id=\"section_226705990\">\n\t\t<div class=\"bg section-bg fill bg-fill  bg-loaded\" >\n\n\t\t\t\n\t\t\t\n\t\t\t\n\n\t\t<\/div>\n\n\t\t<div class=\"section-content relative\">\n\t\t\t\n<div class=\"row row-collapse align-center\"  id=\"row-2035260700\">\n\n\t<div id=\"col-2099608466\" class=\"col small-12 large-12\"  >\n\t\t<div class=\"col-inner text-left\"  >\n\t\t\t\n\t\t\t\n<h5 style=\"text-align: left;\"><span style=\"font-size: 130%;\"><span style=\"color: #ffffff; font-size: 80%;\">You may also like:<\/span><\/span><\/h5>\n\t\t<\/div>\n\t\t\n<style>\n#col-2099608466 > .col-inner {\n  padding: 0px 0px 0px 0px;\n  margin: 0px 0px 0px 10px;\n}\n<\/style>\n\t<\/div>\n\n\t\n\n<style>\n#row-2035260700 > .col > .col-inner {\n  padding: 0px 0px 4px 0px;\n}\n<\/style>\n<\/div>\n<div class=\"row row-collapse\"  id=\"row-1872836648\">\n\n\t<div id=\"col-430697833\" class=\"col medium-3 small-12 large-3\"  >\n\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\n\t<div class=\"box has-hover   has-hover box-text-bottom\" >\n\n\t\t<div class=\"box-image\" >\n\t\t\t<a href=\"https:\/\/www.nicolacrivellari.com\/en\/geox\/\"  >\t\t\t<div class=\"image-cover\" style=\"padding-top:50%;\">\n\t\t\t\t<img width=\"1080\" height=\"608\" src=\"https:\/\/www.nicolacrivellari.com\/wp-content\/uploads\/2020\/08\/6_Geox_risultato.jpg\" class=\"attachment- size-\" alt=\"\" loading=\"lazy\" srcset=\"https:\/\/www.nicolacrivellari.com\/wp-content\/uploads\/2020\/08\/6_Geox_risultato.jpg 1080w, https:\/\/www.nicolacrivellari.com\/wp-content\/uploads\/2020\/08\/6_Geox_risultato-300x169.jpg 300w, https:\/\/www.nicolacrivellari.com\/wp-content\/uploads\/2020\/08\/6_Geox_risultato-1024x576.jpg 1024w, https:\/\/www.nicolacrivellari.com\/wp-content\/uploads\/2020\/08\/6_Geox_risultato-768x432.jpg 768w\" sizes=\"(max-width: 1080px) 100vw, 1080px\" \/>\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t<\/a>\t\t<\/div>\n\n\t\t<div class=\"box-text text-center\" >\n\t\t\t<div class=\"box-text-inner\">\n\t\t\t\t\n<h5><span style=\"color: #ffffff;\">Geox Magazine<br \/><\/span><\/h5>\n\t\t\t<\/div>\n\t\t<\/div>\n\t<\/div>\n\t\n\t\t<\/div>\n\t\t\n<style>\n#col-430697833 > .col-inner {\n  padding: 0px 4px 0px 0px;\n}\n<\/style>\n\t<\/div>\n\n\t\n\n\t<div id=\"col-1191969840\" class=\"col medium-3 small-12 large-3\"  >\n\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\n\t<div class=\"box has-hover   has-hover box-text-bottom\" >\n\n\t\t<div class=\"box-image\" >\n\t\t\t<a href=\"https:\/\/www.nicolacrivellari.com\/en\/mta\/\"  >\t\t\t<div class=\"image-cover\" style=\"padding-top:50%;\">\n\t\t\t\t<img width=\"1080\" height=\"608\" src=\"https:\/\/www.nicolacrivellari.com\/wp-content\/uploads\/2020\/08\/7_MTA_risultato.jpg\" class=\"attachment- size-\" alt=\"\" loading=\"lazy\" srcset=\"https:\/\/www.nicolacrivellari.com\/wp-content\/uploads\/2020\/08\/7_MTA_risultato.jpg 1080w, https:\/\/www.nicolacrivellari.com\/wp-content\/uploads\/2020\/08\/7_MTA_risultato-300x169.jpg 300w, https:\/\/www.nicolacrivellari.com\/wp-content\/uploads\/2020\/08\/7_MTA_risultato-1024x576.jpg 1024w, https:\/\/www.nicolacrivellari.com\/wp-content\/uploads\/2020\/08\/7_MTA_risultato-768x432.jpg 768w\" sizes=\"(max-width: 1080px) 100vw, 1080px\" \/>\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t<\/a>\t\t<\/div>\n\n\t\t<div class=\"box-text text-center\" >\n\t\t\t<div class=\"box-text-inner\">\n\t\t\t\t\n<h5><span style=\"color: #ffffff;\">MTA Greenhouse<br \/><\/span><\/h5>\n\t\t\t<\/div>\n\t\t<\/div>\n\t<\/div>\n\t\n\t\t<\/div>\n\t\t\n<style>\n#col-1191969840 > .col-inner {\n  padding: 0px 4px 0px 0px;\n}\n<\/style>\n\t<\/div>\n\n\t\n\n\t<div id=\"col-262995657\" class=\"col medium-3 small-12 large-3\"  >\n\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\n\t<div class=\"box has-hover   has-hover box-text-bottom\" >\n\n\t\t<div class=\"box-image\" >\n\t\t\t<a href=\"https:\/\/www.nicolacrivellari.com\/en\/movember\/\"  >\t\t\t<div class=\"image-cover\" style=\"padding-top:50%;\">\n\t\t\t\t<img width=\"1080\" height=\"608\" src=\"https:\/\/www.nicolacrivellari.com\/wp-content\/uploads\/2020\/08\/8_Movember_risultato.jpg\" class=\"attachment- size-\" alt=\"\" loading=\"lazy\" srcset=\"https:\/\/www.nicolacrivellari.com\/wp-content\/uploads\/2020\/08\/8_Movember_risultato.jpg 1080w, https:\/\/www.nicolacrivellari.com\/wp-content\/uploads\/2020\/08\/8_Movember_risultato-300x169.jpg 300w, https:\/\/www.nicolacrivellari.com\/wp-content\/uploads\/2020\/08\/8_Movember_risultato-1024x576.jpg 1024w, https:\/\/www.nicolacrivellari.com\/wp-content\/uploads\/2020\/08\/8_Movember_risultato-768x432.jpg 768w\" sizes=\"(max-width: 1080px) 100vw, 1080px\" \/>\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t<\/a>\t\t<\/div>\n\n\t\t<div class=\"box-text text-center\" >\n\t\t\t<div class=\"box-text-inner\">\n\t\t\t\t\n<h5><span style=\"color: #ffffff;\">Movember. Uomini come te<\/span><\/h5>\n\t\t\t<\/div>\n\t\t<\/div>\n\t<\/div>\n\t\n\t\t<\/div>\n\t\t\n<style>\n#col-262995657 > .col-inner {\n  padding: 0px 4px 0px 0px;\n}\n<\/style>\n\t<\/div>\n\n\t\n\n\t<div id=\"col-406902426\" class=\"col medium-3 small-12 large-3\"  >\n\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\n\t<div class=\"box has-hover   has-hover box-text-bottom\" >\n\n\t\t<div class=\"box-image\" >\n\t\t\t<a href=\"https:\/\/www.nicolacrivellari.com\/en\/marvis\/\"  >\t\t\t<div class=\"image-cover\" style=\"padding-top:50%;\">\n\t\t\t\t<img width=\"1080\" height=\"608\" src=\"https:\/\/www.nicolacrivellari.com\/wp-content\/uploads\/2020\/08\/2_Marvis_risultato.jpg\" class=\"attachment- size-\" alt=\"marvis_project_cover\" loading=\"lazy\" srcset=\"https:\/\/www.nicolacrivellari.com\/wp-content\/uploads\/2020\/08\/2_Marvis_risultato.jpg 1080w, https:\/\/www.nicolacrivellari.com\/wp-content\/uploads\/2020\/08\/2_Marvis_risultato-300x169.jpg 300w, https:\/\/www.nicolacrivellari.com\/wp-content\/uploads\/2020\/08\/2_Marvis_risultato-1024x576.jpg 1024w, https:\/\/www.nicolacrivellari.com\/wp-content\/uploads\/2020\/08\/2_Marvis_risultato-768x432.jpg 768w\" sizes=\"(max-width: 1080px) 100vw, 1080px\" \/>\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t<\/a>\t\t<\/div>\n\n\t\t<div class=\"box-text text-center\" >\n\t\t\t<div class=\"box-text-inner\">\n\t\t\t\t\n<h5><span style=\"color: #ffffff;\">DoDo Jewels<\/span><\/h5>\n\t\t\t<\/div>\n\t\t<\/div>\n\t<\/div>\n\t\n\t\t<\/div>\n\t\t\n<style>\n#col-406902426 > .col-inner {\n  padding: 0px 5px 0px 0px;\n  margin: 0px -0 0px 0px;\n}\n<\/style>\n\t<\/div>\n\n\t\n<\/div>\n\t\t<\/div>\n\n\t\t\n<style>\n#section_226705990 {\n  padding-top: 0px;\n  padding-bottom: 0px;\n  background-color: rgb(33, 33, 33);\n}\n<\/style>\n\t<\/section>\n\t\n\t<section class=\"section show-for-small\" id=\"section_888719872\">\n\t\t<div class=\"bg section-bg fill bg-fill  bg-loaded\" >\n\n\t\t\t\n\t\t\t\n\t\t\t\n\n\t\t<\/div>\n\n\t\t<div class=\"section-content relative\">\n\t\t\t\n<div class=\"row row-collapse align-center show-for-small\"  id=\"row-2126694116\">\n\n\t<div id=\"col-1912544275\" class=\"col small-12 large-12\"  >\n\t\t<div class=\"col-inner text-left\"  >\n\t\t\t\n\t\t\t\n<h5 style=\"text-align: left;\"><span style=\"font-size: 130%;\"><span style=\"color: #ffffff; font-size: 80%;\">Scopri anche:<\/span><br \/><\/span><\/h5>\n\t\t<\/div>\n\t\t\n<style>\n#col-1912544275 > .col-inner {\n  padding: 0px 0px 0px 0px;\n  margin: 0px 0px 0px 10px;\n}\n<\/style>\n\t<\/div>\n\n\t\n\n<style>\n#row-2126694116 > .col > .col-inner {\n  padding: 0px 0px 4px 0px;\n}\n<\/style>\n<\/div>\n<div class=\"row row-collapse\"  id=\"row-838828192\">\n\n\t<div id=\"col-1743629847\" class=\"col medium-3 small-12 large-3\"  >\n\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\n\t<div class=\"box has-hover   has-hover box-text-bottom\" >\n\n\t\t<div class=\"box-image\" >\n\t\t\t<a href=\"https:\/\/www.nicolacrivellari.com\/geox\/\"  >\t\t\t<div class=\"image-cover\" style=\"padding-top:50%;\">\n\t\t\t\t<img width=\"1080\" height=\"608\" src=\"https:\/\/www.nicolacrivellari.com\/wp-content\/uploads\/2020\/08\/6_Geox_risultato.jpg\" class=\"attachment- size-\" alt=\"\" loading=\"lazy\" srcset=\"https:\/\/www.nicolacrivellari.com\/wp-content\/uploads\/2020\/08\/6_Geox_risultato.jpg 1080w, https:\/\/www.nicolacrivellari.com\/wp-content\/uploads\/2020\/08\/6_Geox_risultato-300x169.jpg 300w, https:\/\/www.nicolacrivellari.com\/wp-content\/uploads\/2020\/08\/6_Geox_risultato-1024x576.jpg 1024w, https:\/\/www.nicolacrivellari.com\/wp-content\/uploads\/2020\/08\/6_Geox_risultato-768x432.jpg 768w\" sizes=\"(max-width: 1080px) 100vw, 1080px\" \/>\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t<\/a>\t\t<\/div>\n\n\t\t<div class=\"box-text text-center\" >\n\t\t\t<div class=\"box-text-inner\">\n\t\t\t\t\n<h5><span style=\"color: #ffffff;\">Geox Magazine<br \/><\/span><\/h5>\n\t\t\t<\/div>\n\t\t<\/div>\n\t<\/div>\n\t\n\t\t<\/div>\n\t\t\n<style>\n#col-1743629847 > .col-inner {\n  padding: 0px 4px 0px 0px;\n}\n<\/style>\n\t<\/div>\n\n\t\n<\/div>\n\t\t<\/div>\n\n\t\t\n<style>\n#section_888719872 {\n  padding-top: 0px;\n  padding-bottom: 0px;\n  background-color: rgb(33, 33, 33);\n}\n<\/style>\n\t<\/section>\n\t\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":2,"comment_status":"closed","ping_status":"closed","template":"page-transparent-header.php","meta":[],"_links":{"self":[{"href":"https:\/\/www.nicolacrivellari.com\/en\/wp-json\/wp\/v2\/pages\/9885"}],"collection":[{"href":"https:\/\/www.nicolacrivellari.com\/en\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.nicolacrivellari.com\/en\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.nicolacrivellari.com\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.nicolacrivellari.com\/en\/wp-json\/wp\/v2\/comments?post=9885"}],"version-history":[{"count":9,"href":"https:\/\/www.nicolacrivellari.com\/en\/wp-json\/wp\/v2\/pages\/9885\/revisions"}],"predecessor-version":[{"id":9966,"href":"https:\/\/www.nicolacrivellari.com\/en\/wp-json\/wp\/v2\/pages\/9885\/revisions\/9966"}],"wp:attachment":[{"href":"https:\/\/www.nicolacrivellari.com\/en\/wp-json\/wp\/v2\/media?parent=9885"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}